{"id":56523,"date":"2026-04-22T10:16:20","date_gmt":"2026-04-22T08:16:20","guid":{"rendered":"https:\/\/librairie7l.com\/?post_type=product&#038;p=56523"},"modified":"2026-05-13T08:57:55","modified_gmt":"2026-05-13T06:57:55","slug":"les-paysages-interieurs-de-toyo-ito-2","status":"publish","type":"product","link":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/","title":{"rendered":"LES PAYSAGES INT\u00c9RIEURS DE TOYO ITO"},"content":{"rendered":"<p>Sept entretiens avec Toyo Ito pour d\u00e9couvrir son oeuvre.<br \/>\nJe veux cr\u00e9er une architecture qui soit comme un jardin, o\u00f9 l&#8217;on puisse \u00e0 un moment passer de l&#8217;int\u00e9rieur vers le monde ext\u00e9rieur sans que l&#8217;on s&#8217;en rende compte.<br \/>\n&#8211; Toy&#333; It&#333;<br \/>\nArchitecte de renomm\u00e9e internationale et laur\u00e9at du prix Pritzker en 2013, Toy&#333; It&#333; livre \u00e0 travers sept entretiens ses inspirations les plus intimes.<br \/>\nLe lac Suwa jouxtant la maison de son enfance, le bruit des vagues au r\u00e9veil ou la vapeur blanche s&#8217;\u00e9chappant de la source chaude du jardin en hiver sont autant d&#8217;\u00e9l\u00e9ments qui, avant m\u00eame qu&#8217;il ne d\u00e9bute sa carri\u00e8re, ont aliment\u00e9 sa r\u00e9flexion sur la perm\u00e9abilit\u00e9 entre les espaces int\u00e9rieurs et ext\u00e9rieurs, au coeur de son travail.<br \/>\nAinsi a-t-il imagin\u00e9 la m\u00e9diath\u00e8que de Sendai comme une for\u00eat, travers\u00e9e d&#8217;\u00e9tranges arbres (des colonnes d&#8217;acier) ; la Maison \u00e0 Nakano, en forme de U et \u00e9pousant les contours d&#8217;une lumineuse cour int\u00e9rieure ; ou l&#8217;Op\u00e9ra national de Taichung, dont le chemin relie l&#8217;espace de concert \u00e0 l&#8217;ext\u00e9rieur.<br \/>\n\u00c0 travers son oeuvre, il nous invite \u00e0 nous d\u00e9placer, \u00e0 voir et \u00e0 ressentir autrement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sept entretiens avec Toyo Ito pour d\u00e9couvrir son oeuvre. Je veux cr\u00e9er une architecture qui soit comme un jardin, o\u00f9 l&#8217;on puisse \u00e0 un moment passer de l&#8217;int\u00e9rieur vers le monde ext\u00e9rieur sans que l&#8217;on s&#8217;en rende compte. &#8211; Toy&#333; It&#333; Architecte de renomm\u00e9e internationale et laur\u00e9at du prix Pritzker en 2013, Toy&#333; It&#333; livre [&hellip;]<\/p>\n","protected":false},"featured_media":56521,"template":"","meta":[],"product_cat":[2948],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Paysages int\u00e9rieurs de Toyo Ito - Librairie 7L<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Paysages int\u00e9rieurs de Toyo Ito - Librairie 7L\" \/>\n<meta property=\"og:description\" content=\"Sept entretiens avec Toyo Ito pour d\u00e9couvrir son oeuvre. Je veux cr\u00e9er une architecture qui soit comme un jardin, o\u00f9 l&#8217;on puisse \u00e0 un moment passer de l&#8217;int\u00e9rieur vers le monde ext\u00e9rieur sans que l&#8217;on s&#8217;en rende compte. &#8211; Toy&#333; It&#333; Architecte de renomm\u00e9e internationale et laur\u00e9at du prix Pritzker en 2013, Toy&#333; It&#333; livre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Librairie 7L\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T06:57:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/librairie7l.com\/wp-content\/uploads\/2025\/12\/9782363084361_1_75.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"918\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/\",\"url\":\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/\",\"name\":\"Les Paysages int\u00e9rieurs de Toyo Ito - Librairie 7L\",\"isPartOf\":{\"@id\":\"https:\/\/librairie7l.com\/en\/#website\"},\"datePublished\":\"2026-04-22T08:16:20+00:00\",\"dateModified\":\"2026-05-13T06:57:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/librairie7l.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/librairie7l.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LES PAYSAGES INT\u00c9RIEURS DE TOYO ITO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/librairie7l.com\/en\/#website\",\"url\":\"https:\/\/librairie7l.com\/en\/\",\"name\":\"Librairie 7L\",\"description\":\"Librairie fond\u00e9e en 1999 par Karl Lagerfeld \u00e0 Paris\",\"publisher\":{\"@id\":\"https:\/\/librairie7l.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/librairie7l.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/librairie7l.com\/en\/#organization\",\"name\":\"Librairie 7L\",\"url\":\"https:\/\/librairie7l.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":227,\"height\":301,\"caption\":\"Librairie 7L\"},\"image\":{\"@id\":\"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Paysages int\u00e9rieurs de Toyo Ito - Librairie 7L","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/","og_locale":"en_US","og_type":"article","og_title":"Les Paysages int\u00e9rieurs de Toyo Ito - Librairie 7L","og_description":"Sept entretiens avec Toyo Ito pour d\u00e9couvrir son oeuvre. Je veux cr\u00e9er une architecture qui soit comme un jardin, o\u00f9 l&#8217;on puisse \u00e0 un moment passer de l&#8217;int\u00e9rieur vers le monde ext\u00e9rieur sans que l&#8217;on s&#8217;en rende compte. &#8211; Toy&#333; It&#333; Architecte de renomm\u00e9e internationale et laur\u00e9at du prix Pritzker en 2013, Toy&#333; It&#333; livre [&hellip;]","og_url":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/","og_site_name":"Librairie 7L","article_modified_time":"2026-05-13T06:57:55+00:00","og_image":[{"width":600,"height":918,"url":"https:\/\/librairie7l.com\/wp-content\/uploads\/2025\/12\/9782363084361_1_75.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/","url":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/","name":"Les Paysages int\u00e9rieurs de Toyo Ito - Librairie 7L","isPartOf":{"@id":"https:\/\/librairie7l.com\/en\/#website"},"datePublished":"2026-04-22T08:16:20+00:00","dateModified":"2026-05-13T06:57:55+00:00","breadcrumb":{"@id":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/librairie7l.com\/en\/produit\/les-paysages-interieurs-de-toyo-ito-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/librairie7l.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/librairie7l.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"LES PAYSAGES INT\u00c9RIEURS DE TOYO ITO"}]},{"@type":"WebSite","@id":"https:\/\/librairie7l.com\/en\/#website","url":"https:\/\/librairie7l.com\/en\/","name":"Librairie 7L","description":"Librairie fond\u00e9e en 1999 par Karl Lagerfeld \u00e0 Paris","publisher":{"@id":"https:\/\/librairie7l.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/librairie7l.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/librairie7l.com\/en\/#organization","name":"Librairie 7L","url":"https:\/\/librairie7l.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png","width":227,"height":301,"caption":"Librairie 7L"},"image":{"@id":"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product\/56523"}],"collection":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/media\/56521"}],"wp:attachment":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/media?parent=56523"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product_cat?post=56523"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product_tag?post=56523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}