{"id":58484,"date":"2026-07-02T09:17:27","date_gmt":"2026-07-02T07:17:27","guid":{"rendered":"https:\/\/librairie7l.com\/?post_type=product&#038;p=58484"},"modified":"2026-09-02T08:13:44","modified_gmt":"2026-09-02T06:13:44","slug":"la-nature-en-scene-2","status":"publish","type":"product","link":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/","title":{"rendered":"LA NATURE EN SC\u00c8NE"},"content":{"rendered":"<p>Figure des pionniers de la photographie et acteur majeur qui favorisa l&#8217;inscription du m\u00e9dium parmi les avantgardes de la modernit\u00e9 au d\u00e9but du XXe si\u00e8cle, Edward Steichen exp\u00e9rimente tr\u00e8s t\u00f4t les possibilit\u00e9s qu&#8217;offre son art. Fascin\u00e9 par les variations de la lumi\u00e8re dans la nature, il saisit \u00e0 travers l&#8217;objectif les reflets du ciel sur l&#8217;eau, les diffractions des ombres dans les feuillages, l&#8217;\u00e9clat color\u00e9 de p\u00e9tales de fleurs.<br \/>\nJouant des clairs-obscurs tel un peintre, Steichen pose un regard nouveau sur le monde v\u00e9g\u00e9tal : son go\u00fbt pour l&#8217;exp\u00e9rimentation de l&#8217;image photographique fait \u00e9cho \u00e0 celui pour l&#8217;hybridation des fleurs. Jardinier amateur, le photographe cultive ses propres esp\u00e8ces &#8211; il affectionne notamment les delphiniums. Cet ouvrage pr\u00e9sente pour la premi\u00e8re fois la relation singuli\u00e8re qu&#8217;entretint Steichen avec la nature et le jardin.<br \/>\nC\u00e9l\u00e8bre pour ses portraits, le photographe saisit fleurs, arbres et bouquets avec la m\u00eame attention. C&#8217;est dans le jardin, \u00e0 l&#8217;\u00e9gal du studio, que s&#8217;exerce son regard et qu&#8217;il d\u00e9veloppe sa pratique artistique. Du pictorialisme du c\u00e9l\u00e8bre tirage au platinum The Flatiron r\u00e9alis\u00e9 en 1904 \u00e0 New York, o\u00f9 se diffusent les teintes cr\u00e9pusculaires de la ville, aux tirages chromog\u00e8nes dat\u00e9s des ann\u00e9es 1950 qui donnent \u00e0 voir la puissance des couleurs de la campagne du Connecticut, en passant par les natures mortes de bouquets de roses ou de tournesols, les images de Steichen nous immergent dans des atmosph\u00e8res o\u00f9 la lumi\u00e8re dessine les contours et infuse l&#8217;air.<br \/>\nLa puissance chromatique comme celle des noirs et blancs mettent en sc\u00e8ne une nature regard\u00e9e dans toute sa diversit\u00e9, sauvage comme cultiv\u00e9e. Cette derni\u00e8re est pour le photographe un vaste champ exploratoire, comme en t\u00e9moignent les collections luxembourgeoises ici pr\u00e9sent\u00e9es, celles du Mus\u00e9e national d&#8217;arch\u00e9ologie, d&#8217;histoire et d&#8217;art, et celles de la BCEE et de la Phototh\u00e8que de l&#8217;Etat du Luxembourg.<br \/>\nCompl\u00e9t\u00e9 de textes d&#8217;historiens internationaux de la photographie, ce corpus visuel souligne, pour la premi\u00e8re fois, l&#8217;importance du monde v\u00e9g\u00e9tal dans les recherches esth\u00e9tiques d&#8217;un grand ma\u00eetre du XXe si\u00e8cle. Cette publication accompagnera l&#8217;exposition Steichen et la nature aux Rencontres d&#8217;Arles \u00e0 l&#8217;\u00e9t\u00e9 2026 et s&#8217;inscrira dans le cadre du Bicentenaire du m\u00e9dium.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Figure des pionniers de la photographie et acteur majeur qui favorisa l&#8217;inscription du m\u00e9dium parmi les avantgardes de la modernit\u00e9 au d\u00e9but du XXe si\u00e8cle, Edward Steichen exp\u00e9rimente tr\u00e8s t\u00f4t les possibilit\u00e9s qu&#8217;offre son art. Fascin\u00e9 par les variations de la lumi\u00e8re dans la nature, il saisit \u00e0 travers l&#8217;objectif les reflets du ciel sur [&hellip;]<\/p>\n","protected":false},"featured_media":58768,"template":"","meta":[],"product_cat":[2948,2958,2961],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La nature en sc\u00e8ne - Librairie 7L<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nature en sc\u00e8ne - Librairie 7L\" \/>\n<meta property=\"og:description\" content=\"Figure des pionniers de la photographie et acteur majeur qui favorisa l&#8217;inscription du m\u00e9dium parmi les avantgardes de la modernit\u00e9 au d\u00e9but du XXe si\u00e8cle, Edward Steichen exp\u00e9rimente tr\u00e8s t\u00f4t les possibilit\u00e9s qu&#8217;offre son art. Fascin\u00e9 par les variations de la lumi\u00e8re dans la nature, il saisit \u00e0 travers l&#8217;objectif les reflets du ciel sur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Librairie 7L\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T06:13:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/\",\"url\":\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/\",\"name\":\"La nature en sc\u00e8ne - Librairie 7L\",\"isPartOf\":{\"@id\":\"https:\/\/librairie7l.com\/en\/#website\"},\"datePublished\":\"2026-07-02T07:17:27+00:00\",\"dateModified\":\"2026-09-02T06:13:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/librairie7l.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/librairie7l.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LA NATURE EN SC\u00c8NE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/librairie7l.com\/en\/#website\",\"url\":\"https:\/\/librairie7l.com\/en\/\",\"name\":\"Librairie 7L\",\"description\":\"Librairie fond\u00e9e en 1999 par Karl Lagerfeld \u00e0 Paris\",\"publisher\":{\"@id\":\"https:\/\/librairie7l.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/librairie7l.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/librairie7l.com\/en\/#organization\",\"name\":\"Librairie 7L\",\"url\":\"https:\/\/librairie7l.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":227,\"height\":301,\"caption\":\"Librairie 7L\"},\"image\":{\"@id\":\"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nature en sc\u00e8ne - Librairie 7L","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/","og_locale":"en_US","og_type":"article","og_title":"La nature en sc\u00e8ne - Librairie 7L","og_description":"Figure des pionniers de la photographie et acteur majeur qui favorisa l&#8217;inscription du m\u00e9dium parmi les avantgardes de la modernit\u00e9 au d\u00e9but du XXe si\u00e8cle, Edward Steichen exp\u00e9rimente tr\u00e8s t\u00f4t les possibilit\u00e9s qu&#8217;offre son art. Fascin\u00e9 par les variations de la lumi\u00e8re dans la nature, il saisit \u00e0 travers l&#8217;objectif les reflets du ciel sur [&hellip;]","og_url":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/","og_site_name":"Librairie 7L","article_modified_time":"2026-09-02T06:13:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/","url":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/","name":"La nature en sc\u00e8ne - Librairie 7L","isPartOf":{"@id":"https:\/\/librairie7l.com\/en\/#website"},"datePublished":"2026-07-02T07:17:27+00:00","dateModified":"2026-09-02T06:13:44+00:00","breadcrumb":{"@id":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/librairie7l.com\/en\/produit\/la-nature-en-scene-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/librairie7l.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/librairie7l.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"LA NATURE EN SC\u00c8NE"}]},{"@type":"WebSite","@id":"https:\/\/librairie7l.com\/en\/#website","url":"https:\/\/librairie7l.com\/en\/","name":"Librairie 7L","description":"Librairie fond\u00e9e en 1999 par Karl Lagerfeld \u00e0 Paris","publisher":{"@id":"https:\/\/librairie7l.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/librairie7l.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/librairie7l.com\/en\/#organization","name":"Librairie 7L","url":"https:\/\/librairie7l.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"https:\/\/librairie7l.com\/wp-content\/uploads\/2022\/08\/logo-1.png","width":227,"height":301,"caption":"Librairie 7L"},"image":{"@id":"https:\/\/librairie7l.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product\/58484"}],"collection":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/media\/58768"}],"wp:attachment":[{"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/media?parent=58484"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product_cat?post=58484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/librairie7l.com\/en\/wp-json\/wp\/v2\/product_tag?post=58484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}